{"id":21721,"date":"2020-10-15T12:59:00","date_gmt":"2020-10-15T03:59:00","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=21721"},"modified":"2021-01-07T13:49:47","modified_gmt":"2021-01-07T04:49:47","slug":"12009501000580-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/de\/12009501000580-2\/","title":{"rendered":"<span class=\"character_nick\">Die Befreiung<\/span><span class=\"character_name\">Nemesis<\/span>"},"content":{"rendered":"<main id=\"CHARA_333\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_slide03_02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_333_002\" class=\"sec_characate sec_characate--heroes\">Helden<\/p>\r\n                            <p id=\"CHARA_333_003\" class=\"sec_charanick\">Die Befreiung<\/p>\r\n                            <p id=\"CHARA_333_004\" class=\"sec_charaname\">Nemesis<\/p>\r\n                            <p id=\"CHARA_333_005\" class=\"sec_charaappearancetxt\">Erscheint in<\/p>\r\n                            <p id=\"CHARA_333_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Three Houses<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_333_007\" class=\"sec_h2charattl\">Sharena stellt vor!<\/p>\r\n                        <h2 id=\"CHARA_333_008\" class=\"sec_h2charatxt\">Die Befreiung Nemesis<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_333_009\" class=\"sec_dt\">Nemesis, auch genannt: die Befreiung, ist eine legend\u00e4re Figur aus dem alten F\u00f3dlan.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_333_010\" class=\"sec_dt\">Alte Erz\u00e4hlungen besagen, dass die G\u00f6ttin ihm das Flammenwappen und das Schwert des Sch\u00f6pfers verlieh. Zusammen mit seinen Verb\u00fcndeten, den 10 Elitekriegern von F\u00f3dlan, zog er gegen dunkle G\u00f6tter, die B\u00f6ses im Schilde f\u00fchrten, in den Kampf.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_333_011\" class=\"sec_dt\">Als er jedoch diese G\u00f6tter niedergestreckt hatte, wurde Nemesis von Gier \u00fcbermannt. Und so zog er in den Krieg gegen die Kirche der Seiros und das Adrestianische Reich. Dieser Krieg endete erst, als Seiros ihn im Kampf besiegte.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_333_012\" class=\"sec_dt\">Nemesis, der zuvor als Befreier gefeiert worden war, fiel also seinen Ambitionen zum Opfer und fand ein unsch\u00f6nes Ende. Dass er sehr stark ist, steht au\u00dfer Frage! Aber irgendwas sagt mir, dass der Umgang mit diesem Helden schwierig sein k\u00f6nnte&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_333_013\" class=\"sec_h3charatxt\">Beziehungen<\/h3>\r\n                    <h4 id=\"CHARA_333_014\" class=\"sec_h4charatxt\">Byleth<\/h4>\r\n                    <p id=\"CHARA_333_015\" class=\"sec_charatxt\">Kind von Jeralt, dem fr\u00fcheren Kommandanten der Ritter der Seiros. Byleth ist stoisch, doch als Lehrkraft an der Milit\u00e4rakademie \u00e4u\u00dferst bef\u00e4higt. Tr\u00e4gt das Sch\u00f6pferschwert \u2013 die Waffe, die einst von Nemesis gef\u00fchrt wurde.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Helden Die Befreiung Nemesis Erscheint in Fire Emblem: Three Houses Sharena stellt vor! Die Befreiung Nemesis Nemesis, auch genannt: die Befreiung, ist eine legend\u00e4re Figur aus dem alten F\u00f3dlan. Alte Erz\u00e4hlungen besagen, dass die G\u00f6ttin ihm das Flammenwappen und das Schwert des Sch\u00f6pfers verlieh. Zusammen mit seinen Verb\u00fcndeten, den 10 Elitekriegern von F\u00f3dlan, zog er [&hellip;]","protected":false},"author":1,"featured_media":21790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"de_DE","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=21718","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1415,1434,1390],"tags":[1417],"class_list":["post-21721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-heroes","category-ex_works_three_houses","category-stay_heroes","tag-helden","de-DE"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nemesis_king_of_liberation.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-5El","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/21721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=21721"}],"version-history":[{"count":2,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/21721\/revisions"}],"predecessor-version":[{"id":23759,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/21721\/revisions\/23759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/21790"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=21721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=21721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=21721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}