






{"id":43225,"date":"2023-05-29T12:23:39","date_gmt":"2023-05-29T03:23:39","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=43225"},"modified":"2023-06-14T15:59:35","modified_gmt":"2023-06-14T06:59:35","slug":"11002006000955-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/de\/11002006000955-2\/","title":{"rendered":"<span class=\"character_nick\">Donnerfl\u00fcgel<\/span><span class=\"character_name\">Hinoka<\/span>"},"content":{"rendered":"<main id=\"CHARA_850\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_850_002\" class=\"sec_characate sec_characate--legendary_heroes\">Legend\u00e4re Helden<\/p>\r\n                            <p id=\"CHARA_850_003\" class=\"sec_charanick\">Donnerfl\u00fcgel<\/p>\r\n                            <p id=\"CHARA_850_004\" class=\"sec_charaname\">Hinoka<\/p>\r\n                            <p id=\"CHARA_850_005\" class=\"sec_charaappearancetxt\">Erscheint in<\/p>\r\n                            <p id=\"CHARA_850_006\" class=\"sec_charaappearancetxt\">Fire Emblem Fates<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_850_007\" class=\"sec_h2charattl\">Sharena stellt vor!<\/p>\r\n                        <h2 id=\"CHARA_850_008\" class=\"sec_h2charatxt\">Donnerfl\u00fcgel Hinoka<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_850_009\" class=\"sec_dt\">Die Hinoka, die du heute vor dir siehst, ist anders als die, die du vielleicht schon kennst \u2013 sie kommt aus einer Welt, in der ihre Geschichte anders verlaufen ist.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_850_010\" class=\"sec_dt\">Als Prinzessin von Hoshido k\u00e4mpfte Hinoka mit ihren Geschwistern gegen Nohr. Doch w\u00e4hrend des Konflikts verlor sie sowohl ihren \u00e4lteren Bruder Ryoma als auch ihren j\u00fcngeren Bruder Takumi&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_850_011\" class=\"sec_dt\">Hinoka bestieg den Thron von Hoshido und pr\u00e4sentierte sich ihren Untertanen mit Raijinto und Fujin Yumi, den Waffen, die Ryoma und Takumi einst trugen.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_850_012\" class=\"sec_dt\">Jetzt tr\u00e4gt sie die W\u00fcnsche ihrer gefallenen Br\u00fcder im Herzen und zudem die schwere Last, die K\u00f6nigin von Hoshido zu sein. Man sagt, dass ihre W\u00fcrde und Entschlossenheit ganz Hoshido neue Hoffnung gegeben haben!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_850_013\" class=\"sec_h3charatxt\">Beziehungen<\/h3>\r\n                    <h4 id=\"CHARA_850_014\" class=\"sec_h4charatxt\">Ryoma<\/h4>\r\n                    <p id=\"CHARA_850_015\" class=\"sec_charatxt\">Der \u00e4lteste Prinz von Hoshido und Hinokas \u00e4lterer Bruder. Er f\u00fchrt das legend\u00e4re Schwert Raijinto.<\/p>\r\n                    <h4 id=\"CHARA_850_016\" class=\"sec_h4charatxt\">Takumi<\/h4>\r\n                    <p id=\"CHARA_850_017\" class=\"sec_charatxt\">Prinz von Hoshido, der den heiligen Bogen, den Fujin Yumi, f\u00fchrt. Kann mitunter sehr empfindlich reagieren. Hinokas j\u00fcngerer Bruder.<\/p>\r\n                    <h4 id=\"CHARA_850_018\" class=\"sec_h4charatxt\">Sakura<\/h4>\r\n                    <p id=\"CHARA_850_019\" class=\"sec_charatxt\">Prinzessin von Hoshido. Sie ist eine einf\u00fchlsame Heilerin, die mit ihrer Sch\u00fcchternheit zu k\u00e4mpfen hat. Hinokas j\u00fcngere Schwester.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Legend\u00e4re Helden Donnerfl\u00fcgel Hinoka Erscheint in Fire Emblem Fates Sharena stellt vor! Donnerfl\u00fcgel Hinoka Die Hinoka, die du heute vor dir siehst, ist anders als die, die du vielleicht schon kennst \u2013 sie kommt aus einer Welt, in der ihre Geschichte anders verlaufen ist. Als Prinzessin von Hoshido k\u00e4mpfte Hinoka mit ihren Geschwistern gegen Nohr. [&hellip;]","protected":false},"author":1,"featured_media":43409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"de_DE","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=43221","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1432,1390,1388],"tags":[1393],"class_list":["post-43225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_fates","category-stay_heroes","category-legendary_heroes","tag-legendare-helden","de-DE"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-bfb","jetpack_likes_enabled":false,"amp_enabled":false,"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/hinoka_thundering_wings.png","_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/43225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=43225"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/43225\/revisions"}],"predecessor-version":[{"id":43241,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/43225\/revisions\/43241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/43409"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=43225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=43225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=43225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}