






{"id":52792,"date":"2024-07-12T12:29:59","date_gmt":"2024-07-12T03:29:59","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=52792"},"modified":"2024-08-07T16:02:44","modified_gmt":"2024-08-07T07:02:44","slug":"07001005001121-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/de\/07001005001121-2\/","title":{"rendered":"<span class=\"character_nick\">Wilder Ritter<\/span><span class=\"character_name\">Forde<\/span>"},"content":{"rendered":"<main id=\"CHARA_1075\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1075_002\" class=\"sec_characate sec_characate--heroes\">Helden<\/p>\r\n                            <p id=\"CHARA_1075_003\" class=\"sec_charanick\">Wilder Ritter<\/p>\r\n                            <p id=\"CHARA_1075_004\" class=\"sec_charaname\">Forde<\/p>\r\n                            <p id=\"CHARA_1075_005\" class=\"sec_charaappearancetxt\">Erscheint in<\/p>\r\n                            <p id=\"CHARA_1075_006\" class=\"sec_charaappearancetxt\">Fire Emblem: The Sacred Stones<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1075_007\" class=\"sec_h2charattl\">Sharena stellt vor!<\/p>\r\n                        <h2 id=\"CHARA_1075_008\" class=\"sec_h2charatxt\">Wilder Ritter Forde<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1075_009\" class=\"sec_dt\">Das hier ist Forde, ein Held aus Magvel! Er ist ein Getreuer von Ephraim, dem Prinzen von Renais, und einer der Ritter des K\u00f6nigreichs.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1075_010\" class=\"sec_dt\">Forde ist optimistisch und sorglos. Abseits des Schlachtfelds l\u00e4sst er seiner k\u00fcnstlerischen Seele oft freien Lauf und malt oder genie\u00dft ein kleines Nickerchen.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1075_011\" class=\"sec_dt\">Mit seinem geduldigen Freund Kyle verbindet Forde ein sehr enges Band. Die beiden wissen die St\u00e4rken des anderen durchaus zu sch\u00e4tzen, doch Kyle muss manchmal ein ernstes W\u00f6rtchen mit seinem Kameraden reden.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1075_012\" class=\"sec_dt\">Renais war ein friedliches K\u00f6nigreich, bis das Imperium von Grado einmarschierte. Und Forde folgte seinem Herrn, Ephraim, auf das Schlachtfeld!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1075_013\" class=\"sec_h3charatxt\">Beziehungen<\/h3>\r\n                    <h4 id=\"CHARA_1075_014\" class=\"sec_h4charatxt\">Ephraim<\/h4>\r\n                    <p id=\"CHARA_1075_015\" class=\"sec_charatxt\">Prinz von Renais und Eirikas Zwillingsbruder. Seine Schwester liegt ihm sehr am Herzen. Sein Selbstvertrauen bringt ihn manchmal in Gefahr. Forde steht ihm treu zur Seite.<\/p>\r\n                    <h4 id=\"CHARA_1075_016\" class=\"sec_h4charatxt\">Kyle<\/h4>\r\n                    <p id=\"CHARA_1075_017\" class=\"sec_charatxt\">Ein Ritter von Renais, der Ephraim unmittelbar dient. Er ist \u00e4u\u00dferst eifrig und f\u00fcr seine Ernsthaftigkeit bekannt. Fordes Freund und Kamerad.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Helden Wilder Ritter Forde Erscheint in Fire Emblem: The Sacred Stones Sharena stellt vor! Wilder Ritter Forde Das hier ist Forde, ein Held aus Magvel! Er ist ein Getreuer von Ephraim, dem Prinzen von Renais, und einer der Ritter des K\u00f6nigreichs. Forde ist optimistisch und sorglos. Abseits des Schlachtfelds l\u00e4sst er seiner k\u00fcnstlerischen Seele oft [&hellip;]","protected":false},"author":1,"featured_media":52913,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"de_DE","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=52789","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1428,1415,1390],"tags":[1417],"class_list":["post-52792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_the_sacred_stones","category-heroes","category-stay_heroes","tag-helden","de-DE"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/forde_unfettered_knight.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-dJu","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/52792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=52792"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/52792\/revisions"}],"predecessor-version":[{"id":52804,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/52792\/revisions\/52804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/52913"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=52792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=52792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=52792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}