






{"id":10727,"date":"2019-07-05T17:27:31","date_gmt":"2019-07-05T08:27:31","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=10727"},"modified":"2019-08-09T13:42:00","modified_gmt":"2019-08-09T04:42:00","slug":"06010001000398","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-ES\/06010001000398\/","title":{"rendered":"<span class=\"character_nick\">Iliana veraneante<\/span><span class=\"character_name\">Fiora<\/span>"},"content":{"rendered":"<main id=\"CHARA_076\" class=\"main_page character\">\r\n    <article>\r\n        <section class=\"sec sec_character\">\r\n            <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_slide01.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_slide02.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_slide03.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_slide04.png\" alt=\"\" \/>\r\n                <\/li>\r\n            <\/ul>\r\n            <div class=\"sec_charainfoarea flex\">\r\n                <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                <div class=\"sec_charainfo\">\r\n                    <p id=\"CHARA_076_002\" class=\"sec_characate sec_characate--special_heroes\">Hero\u00edna especial<\/p>\r\n                    <p id=\"CHARA_076_003\" class=\"sec_charanick\">Iliana veraneante<\/p>\r\n                    <p id=\"CHARA_076_004\" class=\"sec_charaname\">Fiora<\/p>\r\n                    <p id=\"CHARA_076_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                    <p id=\"CHARA_076_006\" class=\"sec_charaappearancetxt\">Fire Emblem: The Blazing Blade<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/section>\r\n    <\/article>\r\n    <article>\r\n        <section class=\"sec sec_characterarea\">\r\n            <div class=\"sec_h2chara\">\r\n                <p id=\"CHARA_076_007\" class=\"sec_h2charattl\">\u00a1Presentaci\u00f3n de personajes con Sharena!<\/p>\r\n                <h2 id=\"CHARA_076_008\" class=\"sec_h2charatxt\">Iliana veraneante Fiora<\/h2>\r\n            <\/div>\r\n            <dl class=\"sec_dl flex\">\r\n                <dt id=\"CHARA_076_009\" class=\"sec_dt\">Fiora es miembro de los jinetes de pegaso de Ilia. Tanto ella como sus hermanas, Farina y Florina, son conocidas en el reino por ser las tres hermanas que van a lomos de un pegaso.<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_pop01.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_info01.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_076_010\" class=\"sec_dt\">Fiora es la mayor de las tres y dicen que a veces es un pel\u00edn&#8230; estiradilla. Pero ahora que ha llegado el verano, \u00a1se ha soltado la melena con su nuevo traje de ba\u00f1o!<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_pop02.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_info02.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_076_011\" class=\"sec_dt\">Fiora lleva un bonito y elegante traje de ba\u00f1o con encaje. Esta vez, sin embargo, en lugar de la lanza que siempre la acompa\u00f1a, complementa su look con un parasol.<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_pop03.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_info03.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_076_012\" class=\"sec_dt\">Para los h\u00e9roes de tierras nevadas como ella, estar bajo el ardiente sol del verano tiene que ser toda una experiencia. \u00a1Espero que Fiora disfrute de un verano inolvidable!<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_pop04.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian_info04.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n            <\/dl>\r\n            <h3 id=\"CHARA_076_013\" class=\"sec_h3charatxt\">Personajes con los que tiene relaci\u00f3n<\/h3>\r\n            <h4 id=\"CHARA_076_014\" class=\"sec_h4charatxt\">Florina<\/h4>\r\n            <p id=\"CHARA_076_015\" class=\"sec_charatxt\">La m\u00e1s joven de las tres hermanas jinetes pegaso de Ilia. Una chica dulce y t\u00edmida a la que le encantan los animales.<\/p>\r\n            <h4 id=\"CHARA_076_016\" class=\"sec_h4charatxt\">Pent<\/h4>\r\n            <p id=\"CHARA_076_017\" class=\"sec_charatxt\">Pent es el l\u00edder de la Casa Reglay de Etruria y el general mago del ej\u00e9rcito del reino. Le ha ordenado a Fiora que investigue la Isla del Terror, que est\u00e1 envuelta en niebla y repleta de bosques frondosos.<\/p>\r\n        <\/section>\r\n    <\/article>\r\n<\/main>","protected":false},"excerpt":{"rendered":"Hero\u00edna especial Iliana veraneante Fiora Aparece en Fire Emblem: The Blazing Blade \u00a1Presentaci\u00f3n de personajes con Sharena! Iliana veraneante Fiora Fiora es miembro de los jinetes de pegaso de Ilia. Tanto ella como sus hermanas, Farina y Florina, son conocidas en el reino por ser las tres hermanas que van a lomos de un pegaso. [&hellip;]","protected":false},"author":1,"featured_media":10757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_ES","_original_post":"10723","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1427,1405,1390],"tags":[1409],"class_list":["post-10727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_the_blazing_blade","category-special_heroes","category-stay_heroes","tag-heroes-especiales","es-ES"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/fiora_thawed-out_ilian.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-2N1","jetpack_likes_enabled":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/10727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=10727"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/10727\/revisions"}],"predecessor-version":[{"id":10738,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/10727\/revisions\/10738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/10757"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=10727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=10727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=10727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}