






{"id":16588,"date":"2020-03-04T12:32:33","date_gmt":"2020-03-04T03:32:33","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=16588"},"modified":"2020-03-19T16:05:21","modified_gmt":"2020-03-19T07:05:21","slug":"12009006000497-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-ES\/12009006000497-2\/","title":{"rendered":"<span class=\"character_nick\">Azote de la paz<\/span><span class=\"character_name\">Emperador del Fuego<\/span>"},"content":{"rendered":"<main id=\"CHARA_215\" class=\"main_page character\">\r\n    <article>\r\n        <section class=\"sec sec_character\">\r\n            <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_slide01.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_slide02.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_slide03.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_slide04.png\" alt=\"\" \/>\r\n                <\/li>\r\n            <\/ul>\r\n            <div class=\"sec_charainfoarea flex\">\r\n                <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war.png\" alt=\"\" width=\"210\" height=\"190\" \/><\/div>\r\n                <div class=\"sec_charainfo\">\r\n                    <p id=\"CHARA_215_002\" class=\"sec_characate sec_characate--heroes\">H\u00e9roes<\/p>\r\n                    <p id=\"CHARA_215_003\" class=\"sec_charanick\">Azote de la paz<\/p>\r\n                    <p id=\"CHARA_215_004\" class=\"sec_charaname\">Emperador del Fuego<\/p>\r\n                    <p id=\"CHARA_215_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                    <p id=\"CHARA_215_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Three Houses<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/section>\r\n    <\/article>\r\n    <article>\r\n        <section class=\"sec sec_characterarea\">\r\n            <div class=\"sec_h2chara\">\r\n                <p id=\"CHARA_215_007\" class=\"sec_h2charattl\">\u00a1Presentaci\u00f3n de personajes con Sharena!<\/p>\r\n                <h2 id=\"CHARA_215_008\" class=\"sec_h2charatxt\">Azote de la paz Emperador del Fuego<\/h2>\r\n            <\/div>\r\n            <dl class=\"sec_dl flex\">\r\n                <dt id=\"CHARA_215_009\" class=\"sec_dt\">Vaya, esto no es nada f\u00e1cil. Se supone que tengo que presentar al Emperador del Fuego, pero tengo m\u00e1s preguntas que respuestas sobre este h\u00e9roe. As\u00ed que veamos, \u00bfqui\u00e9n es el Emperador del Fuego?<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_pop01.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_info01.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_215_010\" class=\"sec_dt\">Una cosa que s\u00ed s\u00e9 es que el Emperador del Fuego es un grand\u00edsimo guerrero que aspira a restablecer el orden en el mundo. \u00bfA qu\u00e9 se referir\u00e1 exactamente con eso?<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_pop02.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_info02.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_215_011\" class=\"sec_dt\">Parece ser que el Emperador del Fuego, a cuyas \u00f3rdenes trabaja el Caballero Sanguinario, se ha visto implicado en muchos de los incidentes que se han producido en el monasterio de Garreg Mach. \u00bfQu\u00e9 estar\u00e1n tramando?<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_pop03.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_info03.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_215_012\" class=\"sec_dt\">Si bien es cierto que el Emperador del Fuego ha estado actuando a hurtadillas, por alg\u00fan motivo creo que en el fondo no es mala persona. Tiene que haber algo muy importante que le haga actuar as\u00ed\u2026 \u00bfLo averiguaremos alg\u00fan d\u00eda?<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_pop04.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war_info04.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n            <\/dl>\r\n            <h3 id=\"CHARA_215_013\" class=\"sec_h3charatxt\">Personajes con los que tiene relaci\u00f3n<\/h3>\r\n            <h4 id=\"CHARA_215_014\" class=\"sec_h4charatxt\">Caballero Sanguinario<\/h4>\r\n            <p id=\"CHARA_215_015\" class=\"sec_charatxt\">Vasallo del Emperador del Fuego que ans\u00eda medirse con los guerreros m\u00e1s poderosos. Su montura es negra y empu\u00f1a una guada\u00f1a.<\/p>\r\n        <\/section>\r\n    <\/article>\r\n<\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes Azote de la paz Emperador del Fuego Aparece en Fire Emblem: Three Houses \u00a1Presentaci\u00f3n de personajes con Sharena! Azote de la paz Emperador del Fuego Vaya, esto no es nada f\u00e1cil. Se supone que tengo que presentar al Emperador del Fuego, pero tengo m\u00e1s preguntas que respuestas sobre este h\u00e9roe. As\u00ed que veamos, \u00bfqui\u00e9n [&hellip;]","protected":false},"author":1,"featured_media":16674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_ES","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=16582","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1415,1434,1390],"tags":[1422],"class_list":["post-16588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-heroes","category-ex_works_three_houses","category-stay_heroes","tag-heroes-2","es-ES"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/frameemperor_bringer_of_war.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-4jy","jetpack_likes_enabled":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/16588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=16588"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/16588\/revisions"}],"predecessor-version":[{"id":16597,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/16588\/revisions\/16597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/16674"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=16588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=16588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=16588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}