






{"id":48801,"date":"2024-01-17T12:47:53","date_gmt":"2024-01-17T03:47:53","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=48801"},"modified":"2024-02-19T16:06:57","modified_gmt":"2024-02-19T07:06:57","slug":"09008006001054-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-ES\/09008006001054-2\/","title":{"rendered":"<span class=\"character_nick\">Voluntad ind\u00f3mita<\/span><span class=\"character_name\">Tormod<\/span>"},"content":{"rendered":"<main id=\"CHARA_983\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_983_002\" class=\"sec_characate sec_characate--special_heroes\">H\u00e9roes especiales<\/p>\r\n                            <p id=\"CHARA_983_003\" class=\"sec_charanick\">Voluntad ind\u00f3mita<\/p>\r\n                            <p id=\"CHARA_983_004\" class=\"sec_charaname\">Tormod<\/p>\r\n                            <p id=\"CHARA_983_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                            <p id=\"CHARA_983_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Radiant Dawn<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_983_007\" class=\"sec_h2charattl\">\u00a1Presentaci\u00f3n de personajes con Sharena!<\/p>\r\n                        <h2 id=\"CHARA_983_008\" class=\"sec_h2charatxt\">Voluntad ind\u00f3mita Tormod<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_983_009\" class=\"sec_dt\">\u00a1Este es Tormod, el l\u00edder del ej\u00e9rcito de liberaci\u00f3n laguz de Tellius! Est\u00e1 aqu\u00ed hoy con nosotros para celebrar el festival de Nabata&#8230; \u00a1y ha elegido un traje muy especial para la ocasi\u00f3n!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_983_010\" class=\"sec_dt\">Tormod se ha decantado por la ropa ligera y suelta tan caracter\u00edstica de Nabata para soportar mejor el calor del desierto.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_983_011\" class=\"sec_dt\">Tambi\u00e9n lleva una antorcha encendida con un pa\u00f1uelo rojo enrollado que hace juego con su pelo.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_983_012\" class=\"sec_dt\">Tormod ha vivido mucho tiempo en el desierto de Grann, as\u00ed que no ha tenido problemas para adaptarse a la moda del desierto de Nabata. \u00a1Seguro que ser\u00e1 el alma de la fiesta en el festival!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_983_013\" class=\"sec_h3charatxt\">Personajes con los que tiene relaci\u00f3n<\/h3>\r\n                    <h4 id=\"CHARA_983_014\" class=\"sec_h4charatxt\">Muarim<\/h4>\r\n                    <p id=\"CHARA_983_015\" class=\"sec_charatxt\">Guerrero del ej\u00e9rcito de liberaci\u00f3n laguz. Comparte un estrecho v\u00ednculo con Tormod.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes especiales Voluntad ind\u00f3mita Tormod Aparece en Fire Emblem: Radiant Dawn \u00a1Presentaci\u00f3n de personajes con Sharena! Voluntad ind\u00f3mita Tormod \u00a1Este es Tormod, el l\u00edder del ej\u00e9rcito de liberaci\u00f3n laguz de Tellius! Est\u00e1 aqu\u00ed hoy con nosotros para celebrar el festival de Nabata&#8230; \u00a1y ha elegido un traje muy especial para la ocasi\u00f3n! Tormod se ha [&hellip;]","protected":false},"author":1,"featured_media":48888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_ES","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=48795","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1405,1390,1430],"tags":[1409],"class_list":["post-48801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-special_heroes","category-stay_heroes","category-ex_works_radiant_dawn","tag-heroes-especiales","es-ES"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/topak_indomitable_will.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-cH7","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/48801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=48801"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/48801\/revisions"}],"predecessor-version":[{"id":48814,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/48801\/revisions\/48814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/48888"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=48801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=48801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=48801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}