






{"id":6634,"date":"2019-01-29T19:08:00","date_gmt":"2019-01-29T10:08:00","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=6634"},"modified":"2019-07-10T16:13:25","modified_gmt":"2019-07-10T07:13:25","slug":"tiki_legendary_dragon","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-ES\/tiki_legendary_dragon\/","title":{"rendered":"<span class=\"character_nick\">La diosa legendaria<\/span><span class=\"character_name\">Tiki<\/span>"},"content":{"rendered":"<main id=\"chara_022\" class=\"main_page character\">\r\n    <article>\r\n        <section class=\"sec sec_character\">\r\n            <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_slide01.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_slide02.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_slide03.png\" alt=\"\" \/>\r\n                <\/li>\r\n                <li class=\"sec_li sec_li--character\">\r\n                    <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_slide04.png\" alt=\"\" \/>\r\n                <\/li>\r\n            <\/ul>\r\n            <div class=\"sec_charainfoarea flex\">\r\n                <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                <div class=\"sec_charainfo\">\r\n                    <p id=\"CHARA_022_002\" class=\"sec_characate sec_characate--legendary_heroes\">H\u00e9roes legendarios<\/p>\r\n                    <p id=\"CHARA_022_003\" class=\"sec_charanick\">La diosa legendaria<\/p>\r\n                    <p id=\"CHARA_022_004\" class=\"sec_charaname\">Tiki<\/p>\r\n                    <p id=\"CHARA_022_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                    <p id=\"CHARA_022_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Mystery of the Emblem<\/p>\r\n                <\/div>\r\n            <\/div>\r\n        <\/section>\r\n    <\/article>\r\n    <article>\r\n        <section class=\"sec sec_characterarea\">\r\n            <div class=\"sec_h2chara\">\r\n                <p id=\"CHARA_022_007\" class=\"sec_h2charattl\">\u00a1Presentaci\u00f3n de personajes con Sharena!<\/p>\r\n                <h2 id=\"CHARA_022_008\" class=\"sec_h2charatxt\">La diosa legendaria Tiki<\/h2>\r\n            <\/div>\r\n            <dl class=\"sec_dl flex\">\r\n                <dt id=\"CHARA_022_009\" class=\"sec_dt\">\u00a1Aqu\u00ed est\u00e1 Tiki! \u00bfA que es una ricura? Pero \u00a1las apariencias enga\u00f1an! Ni te imaginas el poder que tiene esta mujer.<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_pop01.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_info01.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_022_010\" class=\"sec_dt\">Es hija de la legendaria Naga, una poderosa dragona. Como lo oyes: Tiki es una manakete capaz de transformarse en una dragona durante la batalla.<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_pop02.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_info02.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_022_011\" class=\"sec_dt\">Temerosa de que su poder devastara el planeta, Tiki pas\u00f3 muchos a\u00f1os durmiendo. Pero \u00a1muchos, muchos! Creo que tiene m\u00e1s de mil a\u00f1os.<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_pop03.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_info03.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n                <dt id=\"CHARA_022_012\" class=\"sec_dt\">Por sus venas corre la sangre de un drag\u00f3n de f\u00e1bula. Yo creo que solo con eso ya se podr\u00eda decir que es una hero\u00edna legendaria. \u00a1Espero que podamos convencerla de que se una a la causa!<\/dt>\r\n                <dd class=\"sec_dd\">\r\n                    <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_pop04.png\" class=\"popup-image\">\r\n                        <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon_info04.png\" alt=\"\" \/>\r\n                    <\/a>\r\n                <\/dd>\r\n            <\/dl>\r\n            <h3 id=\"CHARA_022_013\" class=\"sec_h3charatxt\">Personajes con los que tiene relaci\u00f3n<\/h3>\r\n            <h4 id=\"CHARA_022_014\" class=\"sec_h4charatxt\">Marth<\/h4>\r\n            <p id=\"CHARA_022_015\" class=\"sec_charatxt\">Pr\u00edncipe del reino de Altea, que lucha por devolver al reino el lugar que le corresponde. En Fire Emblem: Shadow Dragon, rescat\u00f3 y protegi\u00f3 a Tiki, que estaba siendo manipulada.<\/p>\r\n        <\/section>\r\n    <\/article>\r\n<\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes legendarios La diosa legendaria Tiki Aparece en Fire Emblem: Mystery of the Emblem \u00a1Presentaci\u00f3n de personajes con Sharena! La diosa legendaria Tiki \u00a1Aqu\u00ed est\u00e1 Tiki! \u00bfA que es una ricura? Pero \u00a1las apariencias enga\u00f1an! Ni te imaginas el poder que tiene esta mujer. Es hija de la legendaria Naga, una poderosa dragona. Como lo [&hellip;]","protected":false},"author":1,"featured_media":6763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_ES","_original_post":"6629","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1424,1390,1388],"tags":[1395],"class_list":["post-6634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_mystery_of_the_emblem","category-stay_heroes","category-legendary_heroes","tag-heroes-legendarios","es-ES"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tiki_legendary_dragon.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-1J0","jetpack_likes_enabled":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/6634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=6634"}],"version-history":[{"count":2,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/6634\/revisions"}],"predecessor-version":[{"id":6861,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/6634\/revisions\/6861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/6763"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=6634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=6634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=6634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}