






{"id":18180,"date":"2020-05-07T10:37:36","date_gmt":"2020-05-07T01:37:36","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=18180"},"modified":"2020-06-03T13:13:59","modified_gmt":"2020-06-03T04:13:59","slug":"09001501000515-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-MX\/09001501000515-2\/","title":{"rendered":"<span class=\"character_nick\">Fervor desatado<\/span><span class=\"character_name\">Ike<\/span>"},"content":{"rendered":"<main id=\"CHARA_243\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_243_002\" class=\"sec_characate sec_characate--heroes\">H\u00e9roes<\/p>\r\n                            <p id=\"CHARA_243_003\" class=\"sec_charanick\">Fervor desatado<\/p>\r\n                            <p id=\"CHARA_243_004\" class=\"sec_charaname\">Ike<\/p>\r\n                            <p id=\"CHARA_243_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                            <p id=\"CHARA_243_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Radiant Dawn<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_243_007\" class=\"sec_h2charattl\">\u00a1Sharena te contar\u00e1 de \u00e9l!<\/p>\r\n                        <h2 id=\"CHARA_243_008\" class=\"sec_h2charatxt\">Fervor desatado Ike<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_243_009\" class=\"sec_dt\">Ike tiende a ser callado y distante, pero hoy tiene un aire amenazante&#8230; No hice nada para molestarlo, \u00bfverdad?<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_243_010\" class=\"sec_dt\">Ay, no&#8230; \u00a1Parece que su comportamiento extra\u00f1o se debe a una energ\u00eda ca\u00f3tica! Me da muy mala espina&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_pop02-1.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_info02-1.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_243_011\" class=\"sec_dt\">El padre de Ike, Greil, tambi\u00e9n fue afectado por una energ\u00eda ca\u00f3tica y se puso igual. Dicen que algo terrible sucedi\u00f3 despu\u00e9s&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_243_012\" class=\"sec_dt\">\u00a1Bueno, de cualquier modo! Parece que tendremos que esperar hasta que la energ\u00eda ca\u00f3tica se desvanezca. \u00a1Espero que empiece a sentirse mejor pronto!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_243_013\" class=\"sec_h3charatxt\">Personajes relacionados<\/h3>\r\n                    <h4 id=\"CHARA_243_014\" class=\"sec_h4charatxt\">Mist<\/h4>\r\n                    <p id=\"CHARA_243_015\" class=\"sec_charatxt\">Es una chica activa y vivaz que cuida de los mercenarios de Greil. Es la hermana menor de Ike.<\/p>\r\n                    <h4 id=\"CHARA_243_016\" class=\"sec_h4charatxt\">Greil<\/h4>\r\n                    <p id=\"CHARA_243_017\" class=\"sec_charatxt\">Fundador de los mercenarios de Greil. Es el padre de Ike y Mist.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes Fervor desatado Ike Aparece en Fire Emblem: Radiant Dawn \u00a1Sharena te contar\u00e1 de \u00e9l! Fervor desatado Ike Ike tiende a ser callado y distante, pero hoy tiene un aire amenazante&#8230; No hice nada para molestarlo, \u00bfverdad? Ay, no&#8230; \u00a1Parece que su comportamiento extra\u00f1o se debe a una energ\u00eda ca\u00f3tica! Me da muy mala espina&#8230; [&hellip;]","protected":false},"author":1,"featured_media":18133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_MX","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=18173","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1415,1390,1430],"tags":[1422],"class_list":["post-18180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-heroes","category-stay_heroes","category-ex_works_radiant_dawn","tag-heroes-2","es-MX"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/ike_zeal_unleashed.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-4Je","jetpack_likes_enabled":false,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/18180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=18180"}],"version-history":[{"count":3,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/18180\/revisions"}],"predecessor-version":[{"id":18357,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/18180\/revisions\/18357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/18133"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=18180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=18180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=18180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}