






{"id":37256,"date":"2022-09-27T13:28:01","date_gmt":"2022-09-27T04:28:01","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=37256"},"modified":"2022-09-28T13:19:55","modified_gmt":"2022-09-28T04:19:55","slug":"11069022000289-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-MX\/11069022000289-2\/","title":{"rendered":"<span class=\"character_nick\">Esp\u00eda mirona<\/span><span class=\"character_name\">Nina<\/span>"},"content":{"rendered":"<main id=\"CHARA_713\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_713_002\" class=\"sec_characate sec_characate--heroes\">H\u00e9roes<\/p>\r\n                            <p id=\"CHARA_713_003\" class=\"sec_charanick\">Esp\u00eda mirona<\/p>\r\n                            <p id=\"CHARA_713_004\" class=\"sec_charaname\">Nina<\/p>\r\n                            <p id=\"CHARA_713_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                            <p id=\"CHARA_713_006\" class=\"sec_charaappearancetxt\">Fire Emblem Fates<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_713_007\" class=\"sec_h2charattl\">\u00a1Sharena te contar\u00e1 de ella!<\/p>\r\n                        <h2 id=\"CHARA_713_008\" class=\"sec_h2charatxt\">Esp\u00eda mirona Nina<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_713_009\" class=\"sec_dt\">Nina es la hija de Niles, un antiguo ladr\u00f3n que sirve a Nohr. \u00a1Asumi\u00f3 el antiguo oficio de su padre, y una vez lider\u00f3 una banda de nobles ladrones que robaban a los ricos para dar a los pobres!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_713_010\" class=\"sec_dt\">Aunque es valiente y aventurera, a Nina a menudo le resulta dif\u00edcil hablar con los varones. De hecho, cuando habla con un chico por primera vez, \u00a1se pone tan nerviosa que termina tartamudeando!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_713_011\" class=\"sec_dt\">Pero eso no quiere decir que no le gusten los chicos. En realidad, le encanta verlos desde lejos, especialmente cuando se llevan bien, y es entonces cuando despegan sus sue\u00f1os.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_713_012\" class=\"sec_dt\">Y as\u00ed, Nina mira desde una distancia cuidadosa, \u00a1con los ojos brillando como estrellas mientras sue\u00f1a con el amor prohibido!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_713_013\" class=\"sec_h3charatxt\">Personajes relacionados<\/h3>\r\n                    <h4 id=\"CHARA_713_014\" class=\"sec_h4charatxt\">Niles<\/h4>\r\n                    <p id=\"CHARA_713_015\" class=\"sec_charatxt\">Este antiguo malandr\u00edn posee una de las lenguas m\u00e1s afiladas de todo Nohr. Vasallo de Leo y padre de Nina.<\/p>\r\n                    <h4 id=\"CHARA_713_016\" class=\"sec_h4charatxt\">Forrest<\/h4>\r\n                    <p id=\"CHARA_713_017\" class=\"sec_charatxt\">Hijo de Leo. Es de esp\u00edritu bondadoso y compasivo. Tiene un agudo sentido de la est\u00e9tica y le apasiona la costura. Nina se convertir\u00e1 en su vasalla alg\u00fan d\u00eda.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes Esp\u00eda mirona Nina Aparece en Fire Emblem Fates \u00a1Sharena te contar\u00e1 de ella! Esp\u00eda mirona Nina Nina es la hija de Niles, un antiguo ladr\u00f3n que sirve a Nohr. \u00a1Asumi\u00f3 el antiguo oficio de su padre, y una vez lider\u00f3 una banda de nobles ladrones que robaban a los ricos para dar a los [&hellip;]","protected":false},"author":1,"featured_media":37303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_MX","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=37249","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1415,1432,1390],"tags":[1422],"class_list":["post-37256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-heroes","category-ex_works_fates","category-stay_heroes","tag-heroes-2","es-MX"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/eponine_eye_spy.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-9GU","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/37256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=37256"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/37256\/revisions"}],"predecessor-version":[{"id":37265,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/37256\/revisions\/37265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/37303"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=37256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=37256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=37256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}