






{"id":40024,"date":"2023-01-06T13:09:23","date_gmt":"2023-01-06T04:09:23","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=40024"},"modified":"2023-02-10T16:07:03","modified_gmt":"2023-02-10T07:07:03","slug":"06029009000907-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-MX\/06029009000907-2\/","title":{"rendered":"<span class=\"character_nick\">Hechicera vivaz<\/span><span class=\"character_name\">Nino<\/span>"},"content":{"rendered":"<main id=\"CHARA_784\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_784_002\" class=\"sec_characate sec_characate--special_heroes\">H\u00e9roes especiales<\/p>\r\n                            <p id=\"CHARA_784_003\" class=\"sec_charanick\">Hechicera vivaz<\/p>\r\n                            <p id=\"CHARA_784_004\" class=\"sec_charaname\">Nino<\/p>\r\n                            <p id=\"CHARA_784_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                            <p id=\"CHARA_784_006\" class=\"sec_charaappearancetxt\">Fire Emblem: The Blazing Blade<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_784_007\" class=\"sec_h2charattl\">\u00a1Sharena te contar\u00e1 de ella!<\/p>\r\n                        <h2 id=\"CHARA_784_008\" class=\"sec_h2charatxt\">Hechicera vivaz Nino<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_784_009\" class=\"sec_dt\">Nino es la hija adoptada de Brendan, el l\u00edder del Colmillo Negro, un grupo de asesinos que operan desde el reino de Biran, en el continente de Elibe. \u00a1Hoy est\u00e1 de viaje de estudios a la academia de magia en Khadein!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_784_010\" class=\"sec_dt\">\u00a1Aqu\u00ed est\u00e1 luciendo un atuendo habitual de estudiante de la academia con un vestido y una capa hasta la rodilla! \u00a1Ese atuendo le queda muy lindo!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_784_011\" class=\"sec_dt\">Para su arma, Nino est\u00e1 equipada con una br\u00fajula m\u00e1gica que sirve de catalizador para sus hechizos. \u00a1Naturalmente, se abre para indicar d\u00f3nde apunta la aguja!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_784_012\" class=\"sec_dt\">Al parecer, Nino no fue a la escuela ni ha tenido amigos de su edad. Este viaje es una oportunidad muy especial para ella, \u00a1espero que disfrute de probar la vida estudiantil!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_784_013\" class=\"sec_h3charatxt\">Personajes relacionados<\/h3>\r\n                    <h4 id=\"CHARA_784_014\" class=\"sec_h4charatxt\">Ursula<\/h4>\r\n                    <p id=\"CHARA_784_015\" class=\"sec_charatxt\">Miembro despiadada del Colmillo Negro, una cofrad\u00eda de asesinos. Solo acepta servir a alguien que alcance la perfecci\u00f3n. Le encomendaron la misi\u00f3n de deshacerse de Nino cuando la joven maga no logr\u00f3 llevar a cabo un asesinato.<\/p>\r\n                    <h4 id=\"CHARA_784_016\" class=\"sec_h4charatxt\">Jaffar<\/h4>\r\n                    <p id=\"CHARA_784_017\" class=\"sec_charatxt\">Se dice que este implacable asesino del Colmillo Negro es completamente incapaz de sentir ning\u00fan tipo de emoci\u00f3n. Lo llaman \u00c1ngel Mortal. Abandon\u00f3 el Colmillo Negro junto a Nino.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes especiales Hechicera vivaz Nino Aparece en Fire Emblem: The Blazing Blade \u00a1Sharena te contar\u00e1 de ella! Hechicera vivaz Nino Nino es la hija adoptada de Brendan, el l\u00edder del Colmillo Negro, un grupo de asesinos que operan desde el reino de Biran, en el continente de Elibe. \u00a1Hoy est\u00e1 de viaje de estudios a [&hellip;]","protected":false},"author":1,"featured_media":40112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_MX","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=40017","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1427,1405,1390],"tags":[1409],"class_list":["post-40024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_the_blazing_blade","category-special_heroes","category-stay_heroes","tag-heroes-especiales","es-MX"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-apy","jetpack_likes_enabled":false,"amp_enabled":false,"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/nino_spirited_sorcerer.png","_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/40024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=40024"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/40024\/revisions"}],"predecessor-version":[{"id":40033,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/40024\/revisions\/40033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/40112"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=40024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=40024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=40024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}