






{"id":49712,"date":"2024-02-27T10:20:49","date_gmt":"2024-02-27T01:20:49","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=49712"},"modified":"2024-02-28T12:44:07","modified_gmt":"2024-02-28T03:44:07","slug":"05002001000216-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/es-MX\/05002001000216-2\/","title":{"rendered":"<span class=\"character_nick\">Rubor juvenil<\/span><span class=\"character_name\">Lilina<\/span>"},"content":{"rendered":"<main id=\"CHARA_1003\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1003_002\" class=\"sec_characate sec_characate--special_heroes\">H\u00e9roes especiales<\/p>\r\n                            <p id=\"CHARA_1003_003\" class=\"sec_charanick\">Rubor juvenil<\/p>\r\n                            <p id=\"CHARA_1003_004\" class=\"sec_charaname\">Lilina<\/p>\r\n                            <p id=\"CHARA_1003_005\" class=\"sec_charaappearancetxt\">Aparece en<\/p>\r\n                            <p id=\"CHARA_1003_006\" class=\"sec_charaappearancetxt\">Fire Emblem: The Binding Blade<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1003_007\" class=\"sec_h2charattl\">\u00a1Sharena te contar\u00e1 de ella!<\/p>\r\n                        <h2 id=\"CHARA_1003_008\" class=\"sec_h2charatxt\">Rubor juvenil Lilina<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1003_009\" class=\"sec_dt\">Lilina es la hija de H\u00e9ctor, el marqu\u00e9s de Ositia, y viene del continente de Elibe a celebrar con nosotros el D\u00eda de la Devoci\u00f3n. \u00bfNo es elegante su vestido?<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1003_010\" class=\"sec_dt\">Lilina suele usar atuendos con faldas cortas, pero creo que este estilo le queda espectacular. \u00a1Ese dise\u00f1o de color rojo combina muy bien con los detalles y reflejos dorados!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1003_011\" class=\"sec_dt\">Ese debe ser un regalo para alguien que la acompa\u00f1a a la fiesta, pero tambi\u00e9n funciona como arma en caso de que se desate la batalla durante las festividades.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1003_012\" class=\"sec_dt\">Igual me pregunto a qui\u00e9n le dar\u00e1 ese obsequio. Quienquiera que sea, de seguro se pondr\u00e1 muy feliz.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1003_013\" class=\"sec_h3charatxt\">Personajes relacionados<\/h3>\r\n                    <h4 id=\"CHARA_1003_014\" class=\"sec_h4charatxt\">Roy<\/h4>\r\n                    <p id=\"CHARA_1003_015\" class=\"sec_charatxt\">Hijo de Eliwood, marqu\u00e9s de Pherae. Carism\u00e1tico l\u00edder del ej\u00e9rcito de Pherae. Amigo de la infancia de Lilina.<\/p>\r\n                    <h4 id=\"CHARA_1003_016\" class=\"sec_h4charatxt\">H\u00e9ctor<\/h4>\r\n                    <p id=\"CHARA_1003_017\" class=\"sec_charatxt\">Amigo de Eliwood y marqu\u00e9s de Ositia. Prefiere la acci\u00f3n a la formalidad de la corte. Es el padre de Lilina.<\/p>\r\n                    <h4 id=\"CHARA_1003_018\" class=\"sec_h4charatxt\">Cecilia<\/h4>\r\n                    <p id=\"CHARA_1003_019\" class=\"sec_charatxt\">General maga de Etruria. Fue la institutriz de Roy y Lilina cuando eran ni\u00f1os.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9roes especiales Rubor juvenil Lilina Aparece en Fire Emblem: The Binding Blade \u00a1Sharena te contar\u00e1 de ella! Rubor juvenil Lilina Lilina es la hija de H\u00e9ctor, el marqu\u00e9s de Ositia, y viene del continente de Elibe a celebrar con nosotros el D\u00eda de la Devoci\u00f3n. \u00bfNo es elegante su vestido? Lilina suele usar atuendos con [&hellip;]","protected":false},"author":1,"featured_media":49877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"es_MX","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=49704","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1405,1426,1390],"tags":[1409],"class_list":["post-49712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-special_heroes","category-ex_works_the_binding_blade","category-stay_heroes","tag-heroes-especiales","es-MX"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lilina_blush_of_youth.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-cVO","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/49712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=49712"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/49712\/revisions"}],"predecessor-version":[{"id":49722,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/49712\/revisions\/49722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/49877"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=49712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=49712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=49712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}