






{"id":54903,"date":"2024-10-11T12:56:48","date_gmt":"2024-10-11T03:56:48","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=54903"},"modified":"2024-11-06T16:05:22","modified_gmt":"2024-11-06T07:05:22","slug":"12004006001154-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/fr\/12004006001154-2\/","title":{"rendered":"<span class=\"character_nick\">B\u00e9n\u00e9diction sinistre<\/span><span class=\"character_name\">Marianne<\/span>"},"content":{"rendered":"<main id=\"CHARA_1121\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1121_002\" class=\"sec_characate sec_characate--rearmed_heroes\">H\u00e9ros myst\u00e9rieux<\/p>\r\n                            <p id=\"CHARA_1121_003\" class=\"sec_charanick\">B\u00e9n\u00e9diction sinistre<\/p>\r\n                            <p id=\"CHARA_1121_004\" class=\"sec_charaname\">Marianne<\/p>\r\n                            <p id=\"CHARA_1121_005\" class=\"sec_charaappearancetxt\">Appara\u00eet dans<\/p>\r\n                            <p id=\"CHARA_1121_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Three Houses<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1121_007\" class=\"sec_h2charattl\">Sharena vous pr\u00e9sente\u2026<\/p>\r\n                        <h2 id=\"CHARA_1121_008\" class=\"sec_h2charatxt\">B\u00e9n\u00e9diction sinistre Marianne<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1121_009\" class=\"sec_dt\">Marianne nous vient de l&rsquo;Alliance de Leicester en F\u00f3dlan, et elle a acquis de nouveaux pouvoirs, sous la forme de Blutgang, une des reliques de h\u00e9ros\u00a0!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1121_010\" class=\"sec_dt\">Quelle prestance quand elle chevauche son p\u00e9gase\u00a0! Aucun ennemi ne peut rivaliser avec ses puissantes aptitudes guerri\u00e8res ou ses effrayants exploits de magicienne\u00a0!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1121_011\" class=\"sec_dt\">Blutgang \u00e9tait autrefois l&rsquo;arme du h\u00e9ros oubli\u00e9 Maurice, que l&rsquo;on consid\u00e9rait comme l&rsquo;\u00e9gal des Dix Braves du vieux F\u00f3dlan. Marianne l&rsquo;a impr\u00e9gn\u00e9e de sa magie pour en prendre possession\u00a0!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1121_012\" class=\"sec_dt\">Marianne est habituellement pensive et r\u00e9serv\u00e9e, mais ce nouveau pouvoir semble avoir modifi\u00e9 sa personnalit\u00e9. Maintenant qu&rsquo;elle a balay\u00e9 ses incertitudes, j&rsquo;ai h\u00e2te de voir de quoi elle est capable\u00a0!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1121_013\" class=\"sec_h3charatxt\">Personnage li\u00e9 \u00e0<\/h3>\r\n                    <h4 id=\"CHARA_1121_014\" class=\"sec_h4charatxt\">Byleth<\/h4>\r\n                    <p id=\"CHARA_1121_015\" class=\"sec_charatxt\">Ce p\u00e9dagogue sto\u00efque et chevronn\u00e9 de l&rsquo;Acad\u00e9mie des officiers a pour p\u00e8re Jeralt, l&rsquo;ancien capitaine des chevaliers de Seiros. Marianne est son \u00e9l\u00e8ve.<\/p>\r\n                    <h4 id=\"CHARA_1121_016\" class=\"sec_h4charatxt\">Claude<\/h4>\r\n                    <p id=\"CHARA_1121_017\" class=\"sec_charatxt\">H\u00e9ritier de la maison Riegan, famille dirigeante de l&rsquo;Alliance de Leicester, il affiche une attitude d\u00e9sinvolte ainsi qu&rsquo;un vrai talent pour l&rsquo;intrigue. C&rsquo;est le d\u00e9l\u00e9gu\u00e9 des Cerfs d&rsquo;or, la maison \u00e0 laquelle appartient Marianne.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9ros myst\u00e9rieux B\u00e9n\u00e9diction sinistre Marianne Appara\u00eet dans Fire Emblem: Three Houses Sharena vous pr\u00e9sente\u2026 B\u00e9n\u00e9diction sinistre Marianne Marianne nous vient de l&rsquo;Alliance de Leicester en F\u00f3dlan, et elle a acquis de nouveaux pouvoirs, sous la forme de Blutgang, une des reliques de h\u00e9ros\u00a0! Quelle prestance quand elle chevauche son p\u00e9gase\u00a0! Aucun ennemi ne peut rivaliser [&hellip;]","protected":false},"author":1,"featured_media":55119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"fr_FR","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=54895","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1434,1496,1390],"tags":[1501],"class_list":["post-54903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_three_houses","category-rearmed_heroes","category-stay_heroes","tag-heros-mysterieux","fr-FR"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/marianne_cursed_blessing.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-ehx","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/54903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=54903"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/54903\/revisions"}],"predecessor-version":[{"id":54914,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/54903\/revisions\/54914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/55119"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=54903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=54903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=54903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}