






{"id":66609,"date":"2026-05-15T12:20:00","date_gmt":"2026-05-15T03:20:00","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=66609"},"modified":"2026-07-03T13:05:00","modified_gmt":"2026-07-03T04:05:00","slug":"00005001001379-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/fr\/00005001001379-2\/","title":{"rendered":"<span class=\"character_nick\">Mari\u00e9e impliqu\u00e9e<\/span><span class=\"character_name\">Reginn<\/span>"},"content":{"rendered":"<main id=\"CHARA_1381\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1381_002\" class=\"sec_characate sec_characate--rearmed_heroes\">H\u00e9ros myst\u00e9rieux<\/p>\r\n                            <p id=\"CHARA_1381_003\" class=\"sec_charanick\">Mari\u00e9e impliqu\u00e9e<\/p>\r\n                            <p id=\"CHARA_1381_004\" class=\"sec_charaname\">Reginn<\/p>\r\n                            <p id=\"CHARA_1381_005\" class=\"sec_charaappearancetxt\">Appara\u00eet dans<\/p>\r\n                            <p id=\"CHARA_1381_006\" class=\"sec_charaappearancetxt\">Fire Emblem Heroes<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1381_007\" class=\"sec_h2charattl\">Sharena vous pr\u00e9sente\u2026<\/p>\r\n                        <h2 id=\"CHARA_1381_008\" class=\"sec_h2charatxt\">Mari\u00e9e impliqu\u00e9e Reginn<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1381_009\" class=\"sec_dt\">Reginn, princesse de Ni\u00f0avellir, est venue c\u00e9l\u00e9brer le festival des mari\u00e9es dans une tenue fabuleuse pour l&rsquo;occasion !<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1381_010\" class=\"sec_dt\">Voici sa robe, dans les tons blanc et violet. Avec ce corset \u00e0 lacets et ce tissu frang\u00e9 autour de la taille, cette tenue est tr\u00e8s \u00e9labor\u00e9e&nbsp;!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1381_011\" class=\"sec_dt\">Elle porte \u00e9galement un impressionnant pr\u00e9sentoir \u00e0 g\u00e2teaux qui peut faire office de hache tout aussi imposante ! Croiriez-vous que la plupart des d\u00e9corations sur ce g\u00e2teau sont faites uniquement de sucre ? En plus des coups, cette arme risque de donner des caries aux ennemis !<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1381_012\" class=\"sec_dt\">Reginn a dit qu&rsquo;elle essaierait d&rsquo;agir avec maturit\u00e9 et gr\u00e2ce dans cette robe de mari\u00e9e, mais \u00e0 peine le bouquet \u00e9tait-il en l&rsquo;air, elle s&rsquo;est pr\u00e9cipit\u00e9e bille en t\u00eate pour le rattraper !<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1381_013\" class=\"sec_h3charatxt\">Personnage li\u00e9 \u00e0<\/h3>\r\n                    <h4 id=\"CHARA_1381_014\" class=\"sec_h4charatxt\">\u00d3tr<\/h4>\r\n                    <p id=\"CHARA_1381_015\" class=\"sec_charatxt\">Fr\u00e8re adoptif de F\u00e1fnir, roi de Ni\u00f0avellir. Il v\u00e9n\u00e8re son fr\u00e8re et soutient ses ambitions. C&rsquo;est aussi le fr\u00e8re adoptif de Reginn.<\/p>\r\n                    <h4 id=\"CHARA_1381_016\" class=\"sec_h4charatxt\">F\u00e1fnir<\/h4>\r\n                    <p id=\"CHARA_1381_017\" class=\"sec_charatxt\">Roi de Ni\u00f0avellir qui s&rsquo;est hiss\u00e9 jusqu&rsquo;au tr\u00f4ne alors qu&rsquo;il n&rsquo;\u00e9tait qu&rsquo;un simple soldat. Il n&rsquo;a aucun souvenir de son pass\u00e9. Fr\u00e8re adoptif de Reginn.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"H\u00e9ros myst\u00e9rieux Mari\u00e9e impliqu\u00e9e Reginn Appara\u00eet dans Fire Emblem Heroes Sharena vous pr\u00e9sente\u2026 Mari\u00e9e impliqu\u00e9e Reginn Reginn, princesse de Ni\u00f0avellir, est venue c\u00e9l\u00e9brer le festival des mari\u00e9es dans une tenue fabuleuse pour l&rsquo;occasion ! Voici sa robe, dans les tons blanc et violet. Avec ce corset \u00e0 lacets et ce tissu frang\u00e9 autour de la [&hellip;]","protected":false},"author":1,"featured_media":66673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"fr_FR","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=66600","_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1423,1496,1390],"tags":[1501],"class_list":["post-66609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_heroes","category-rearmed_heroes","category-stay_heroes","tag-heros-mysterieux","fr-FR"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-hkl","jetpack_likes_enabled":false,"amp_enabled":false,"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reghin_full-tilt_bride.png","_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=66609"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66609\/revisions"}],"predecessor-version":[{"id":66615,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66609\/revisions\/66615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/66673"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=66609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=66609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=66609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}