






{"id":66358,"date":"2026-05-06T11:59:41","date_gmt":"2026-05-06T02:59:41","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=66358"},"modified":"2026-05-07T11:26:26","modified_gmt":"2026-05-07T02:26:26","slug":"09006001001374-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/it\/09006001001374-2\/","title":{"rendered":"<span class=\"character_nick\">Il re tormenta<\/span><span class=\"character_name\">Tibarn<\/span>"},"content":{"rendered":"<main id=\"CHARA_1375\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1375_002\" class=\"sec_characate sec_characate--rearmed_heroes\">Eroi incantati<\/p>\r\n                            <p id=\"CHARA_1375_003\" class=\"sec_charanick\">Il re tormenta<\/p>\r\n                            <p id=\"CHARA_1375_004\" class=\"sec_charaname\">Tibarn<\/p>\r\n                            <p id=\"CHARA_1375_005\" class=\"sec_charaappearancetxt\">Appare in<\/p>\r\n                            <p id=\"CHARA_1375_006\" class=\"sec_charaappearancetxt\">Fire Emblem: Radiant Dawn<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1375_007\" class=\"sec_h2charattl\">Lascia che sia Sharena a presentarti!<\/p>\r\n                        <h2 id=\"CHARA_1375_008\" class=\"sec_h2charatxt\">Il re tormenta Tibarn<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1375_009\" class=\"sec_dt\">Tibarn \u00e8 il re di Phoenicis, uno dei regni di Tellius. \u00c8 noto per essere un sovrano compassionevole e molto amato dai suoi sudditi, ma ora sembra che ci sia qualcosa di diverso in lui&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1375_010\" class=\"sec_dt\">Oh no! Pare che sia stato sopraffatto dalle sue emozioni negative! Questo spiegherebbe l&#8217;aura sinistra che emana.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1375_011\" class=\"sec_dt\">A quanto pare, Tibarn \u00e8 sempre stato incline al rancore. Quando ha scoperto la verit\u00e0 su ci\u00f2 che accadde durante il massacro di Serenes, non \u00e8 riuscito a contenere la sua furia e cos\u00ec&#8230;<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1375_012\" class=\"sec_dt\">La rabbia di Tibarn \u00e8 una manifestazione del dolore che prova per le vittime di quel massacro. Sono certa che il lato amichevole che tutti conosciamo e amiamo prima o poi torner\u00e0 di nuovo a galla!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1375_013\" class=\"sec_h3charatxt\">Personaggi strettamente collegati<\/h3>\r\n                    <h4 id=\"CHARA_1375_014\" class=\"sec_h4charatxt\">Reyson<\/h4>\r\n                    <p id=\"CHARA_1375_015\" class=\"sec_charatxt\">Principe di Serenes, l&#8217;antico regno degli aironi, e fratello di Leanne. Esile ma dalla volont\u00e0 ferrea. Ammira la forza di Tibarn.<\/p>\r\n                    <h4 id=\"CHARA_1375_016\" class=\"sec_h4charatxt\">Naesala<\/h4>\r\n                    <p id=\"CHARA_1375_017\" class=\"sec_charatxt\">Re di Kilvas e capo del clan dei corvi. Usa la sua astuzia come una lama letale e non ha paura di sporcarsi le mani se serve. \u00c8 una vecchia conoscenza di Tibarn e diventa suo nemico dopo aver collaborato con Begnion.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Eroi incantati Il re tormenta Tibarn Appare in Fire Emblem: Radiant Dawn Lascia che sia Sharena a presentarti! Il re tormenta Tibarn Tibarn \u00e8 il re di Phoenicis, uno dei regni di Tellius. \u00c8 noto per essere un sovrano compassionevole e molto amato dai suoi sudditi, ma ora sembra che ci sia qualcosa di diverso [&hellip;]","protected":false},"author":1,"featured_media":66501,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"it_IT","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=66348","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1496,1389,1430],"tags":[1502],"class_list":["post-66358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-rearmed_heroes","category-new_heroes","category-ex_works_radiant_dawn","tag-eroi-incantati","it-IT"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/tibarn_storm_king.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-hgi","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=66358"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66358\/revisions"}],"predecessor-version":[{"id":66363,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/66358\/revisions\/66363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/66501"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=66358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=66358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=66358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}