






{"id":47958,"date":"2023-12-12T13:05:14","date_gmt":"2023-12-12T04:05:14","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=47958"},"modified":"2024-01-15T16:07:33","modified_gmt":"2024-01-15T07:07:33","slug":"14006003001038-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/pt-BR\/14006003001038-2\/","title":{"rendered":"<span class=\"character_nick\">Emiss\u00e1ria vivaz<\/span><span class=\"character_name\">Yunaka<\/span>"},"content":{"rendered":"<main id=\"CHARA_964\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_964_002\" class=\"sec_characate sec_characate--special_heroes\">Hero\u00edna especial<\/p>\r\n                            <p id=\"CHARA_964_003\" class=\"sec_charanick\">Emiss\u00e1ria vivaz<\/p>\r\n                            <p id=\"CHARA_964_004\" class=\"sec_charaname\">Yunaka<\/p>\r\n                            <p id=\"CHARA_964_005\" class=\"sec_charaappearancetxt\">Aparece em<\/p>\r\n                            <p id=\"CHARA_964_006\" class=\"sec_charaappearancetxt\">Fire Emblem Engage<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_964_007\" class=\"sec_h2charattl\">Sharena apresenta:<\/p>\r\n                        <h2 id=\"CHARA_964_008\" class=\"sec_h2charatxt\">Emiss\u00e1ria vivaz Yunaka<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_964_009\" class=\"sec_dt\">Yunaka veio de Elyos para celebrar o festival de inverno conosco! Ela est\u00e1 com a sua roupa festiva especial para presentear as crian\u00e7as.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_964_010\" class=\"sec_dt\">Eu adoro como a roupa dela combina com o vermelho vibrante do seu cabelo! Ah, que legal! A capa que ela est\u00e1 usando \u00e9 forrada com uma estampa de c\u00e9u estrelado!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_964_011\" class=\"sec_dt\">Espere a\u00ed, que adaga \u00e9 essa que ela trouxe? Parece uma&#8230; decora\u00e7\u00e3o de bolo?! Ah, entendi. \u00c9 uma daqueles palitos que se coloca em bolos!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_964_012\" class=\"sec_dt\">Yunaka est\u00e1 sempre pronta para a a\u00e7\u00e3o, ent\u00e3o ela mal pode esperar para come\u00e7ar a entregar presentes. J\u00e1 posso ouvir a voz dela ecoando pelo c\u00e9u estrelado durante o festival\u2026 \u201cBoas festan\u00e7as!\u201d<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_964_013\" class=\"sec_h3charatxt\">Personagens relacionados<\/h3>\r\n                    <h4 id=\"CHARA_964_014\" class=\"sec_h4charatxt\">Alear<\/h4>\r\n                    <p id=\"CHARA_964_015\" class=\"sec_charatxt\">Descendente do drag\u00e3o divino que despertou de um longo sono. Invoca emblemas para trazer paz ao mundo. Yunaka \u00e9 sua aliada.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Hero\u00edna especial Emiss\u00e1ria vivaz Yunaka Aparece em Fire Emblem Engage Sharena apresenta: Emiss\u00e1ria vivaz Yunaka Yunaka veio de Elyos para celebrar o festival de inverno conosco! Ela est\u00e1 com a sua roupa festiva especial para presentear as crian\u00e7as. Eu adoro como a roupa dela combina com o vermelho vibrante do seu cabelo! Ah, que legal! [&hellip;]","protected":false},"author":1,"featured_media":48047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"pt_BR","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=47948","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1512,1384,1405,1390],"tags":[1460],"class_list":["post-47958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex_works_engage","category-character","category-special_heroes","category-stay_heroes","tag-heroina-especial","pt-BR"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/yunaka_spirited_envoy.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-ctw","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/47958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=47958"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/47958\/revisions"}],"predecessor-version":[{"id":47961,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/47958\/revisions\/47961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/48047"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=47958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=47958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=47958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}