






{"id":50566,"date":"2024-04-03T12:19:28","date_gmt":"2024-04-03T03:19:28","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=50566"},"modified":"2024-05-07T16:02:48","modified_gmt":"2024-05-07T07:02:48","slug":"10001002001081-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/pt-BR\/10001002001081-2\/","title":{"rendered":"<span class=\"character_nick\">Ente destinado<\/span><span class=\"character_name\">Robin<\/span>"},"content":{"rendered":"<main id=\"CHARA_1024\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1024_002\" class=\"sec_characate sec_characate--special_heroes\">Her\u00f3i especial<\/p>\r\n                            <p id=\"CHARA_1024_003\" class=\"sec_charanick\">Ente destinado<\/p>\r\n                            <p id=\"CHARA_1024_004\" class=\"sec_charaname\">Robin<\/p>\r\n                            <p id=\"CHARA_1024_005\" class=\"sec_charaappearancetxt\">Aparece em<\/p>\r\n                            <p id=\"CHARA_1024_006\" class=\"sec_charaappearancetxt\">Fire Emblem Awakening<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1024_007\" class=\"sec_h2charattl\">Sharena apresenta:<\/p>\r\n                        <h2 id=\"CHARA_1024_008\" class=\"sec_h2charatxt\">Ente destinado Robin<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1024_009\" class=\"sec_dt\">Adivinhe quem \u00e9 esse garotinho fofo que acabou de chegar em Askr! S\u00f3 pode ser Robin, o brilhante estrategista de Ylisse, quando era crian\u00e7a!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1024_010\" class=\"sec_dt\">Ao pensar em Robin, sua t\u00fanica costuma ser a primeira coisa que vem \u00e0 mente. E como n\u00e3o poderia ser diferente, sua vers\u00e3o infantil est\u00e1 usando um modelo parecido, s\u00f3 que mais curto e com mangas tr\u00eas quartos!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1024_011\" class=\"sec_dt\">Aparentemente, o tomo que ele carrega \u00e9 especial. Est\u00e1 imbu\u00eddo com o poder de um deus da guerra! Basta ver a joia brilhando na capa para entender que se trata de um objeto verdadeiramente \u00fanico!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1024_012\" class=\"sec_dt\">Acredito que Robin tenha se dedicado ao estudos desde cedo! Esta \u00e9 uma \u00f3tima oportunidade para ele nos visitar em Askr. Ent\u00e3o, espero que ele possa fazer amigos da mesma idade enquanto estiver aqui!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1024_013\" class=\"sec_h3charatxt\">Personagens relacionados<\/h3>\r\n                    <h4 id=\"CHARA_1024_014\" class=\"sec_h4charatxt\">Chrom<\/h4>\r\n                    <p id=\"CHARA_1024_015\" class=\"sec_charatxt\">Pr\u00edncipe de Ylisse e descendente do rei heroico. \u00c9 o l\u00edder dos Guardi\u00f5es. Ele e Robin t\u00eam um v\u00ednculo inquebr\u00e1vel.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Her\u00f3i especial Ente destinado Robin Aparece em Fire Emblem Awakening Sharena apresenta: Ente destinado Robin Adivinhe quem \u00e9 esse garotinho fofo que acabou de chegar em Askr! S\u00f3 pode ser Robin, o brilhante estrategista de Ylisse, quando era crian\u00e7a! Ao pensar em Robin, sua t\u00fanica costuma ser a primeira coisa que vem \u00e0 mente. E [&hellip;]","protected":false},"author":1,"featured_media":50720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"pt_BR","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=50555","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1384,1431,1405,1390],"tags":[1459],"class_list":["post-50566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-character","category-ex_works_awakening","category-special_heroes","category-stay_heroes","tag-heroi-especial","pt-BR"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/reflet_fated_vessel.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-d9A","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/50566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=50566"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/50566\/revisions"}],"predecessor-version":[{"id":50573,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/50566\/revisions\/50573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/50720"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=50566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=50566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=50566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}