






{"id":65691,"date":"2026-03-27T11:56:09","date_gmt":"2026-03-27T02:56:09","guid":{"rendered":"https:\/\/guide.fire-emblem-heroes.com\/?p=65691"},"modified":"2026-04-17T16:00:49","modified_gmt":"2026-04-17T07:00:49","slug":"10069001001361-2","status":"publish","type":"post","link":"https:\/\/guide.fire-emblem-heroes.com\/pt-BR\/10069001001361-2\/","title":{"rendered":"<span class=\"character_nick\">Do despertar<\/span><span class=\"character_name\">Lucina<\/span>"},"content":{"rendered":"<main id=\"CHARA_1361\" class=\"main_page character\">\r\n            <article>\r\n                <section class=\"sec sec_character\">\r\n                    <ul class=\"sec_ul sec_ul--character slick-box\">\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_slide01.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_slide02.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_slide03.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                        <li class=\"sec_li sec_li--character\">\r\n                            <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_slide04.png\" alt=\"\" \/>\r\n                        <\/li>\r\n                    <\/ul>\r\n                    <div class=\"sec_charainfoarea flex\">\r\n                        <div class=\"sec_gif\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening.png\" alt=\"\" width=\"210\" height=\"190\"\/><\/div>\r\n                        <div class=\"sec_charainfo\">\r\n                            <p id=\"CHARA_1361_002\" class=\"sec_characate sec_characate--emblem_heroes\">Hero\u00edna de emblema<\/p>\r\n                            <p id=\"CHARA_1361_003\" class=\"sec_charanick\">Do despertar<\/p>\r\n                            <p id=\"CHARA_1361_004\" class=\"sec_charaname\">Lucina<\/p>\r\n                            <p id=\"CHARA_1361_005\" class=\"sec_charaappearancetxt\">Aparece em<\/p>\r\n                            <p id=\"CHARA_1361_006\" class=\"sec_charaappearancetxt\">Fire Emblem Awakening<br \/>Fire Emblem Engage<\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/section>\r\n            <\/article>\r\n            <article>\r\n                <section class=\"sec sec_characterarea\">\r\n                    <div class=\"sec_h2chara\">\r\n                        <p id=\"CHARA_1361_007\" class=\"sec_h2charattl\">Sharena apresenta:<\/p>\r\n                        <h2 id=\"CHARA_1361_008\" class=\"sec_h2charatxt\">Do despertar Lucina<\/h2>\r\n                    <\/div>\r\n                    <dl class=\"sec_dl flex\">\r\n                        <dt id=\"CHARA_1361_009\" class=\"sec_dt\">O anel da princesa vener\u00e1vel \u00e9 um artefato antigo do continente de Elyos e dentro dele habita Lucina, um dos 12 emblemas que outrora salvaram Elyos!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_pop01.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_info01.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1361_010\" class=\"sec_dt\">Lucina mudou o futuro ao voltar no tempo para salvar o continente de Ylisse. Em Elyos, o emblema dela ajudou Lumera, o drag\u00e3o divino, em sua luta contra Sombron, o terr\u00edvel drag\u00e3o.<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_pop02.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_info02.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1361_011\" class=\"sec_dt\">Mil anos depois, Lucina voltou a Elyos novamente! E desta vez, ela est\u00e1 ajudando o filho de Lumera, Alear, em uma nova batalha contra um Sombron revivido!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_pop03.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_info03.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                        <dt id=\"CHARA_1361_012\" class=\"sec_dt\">Dizem que Lucina confiou no poder dos la\u00e7os com seus aliados para evitar um futuro de desespero. Sei que ela unir\u00e1 o povo da Ordem dos Her\u00f3is e abrir\u00e1 caminho para um futuro cheio de esperan\u00e7a!<\/dt>\r\n                        <dd class=\"sec_dd\">\r\n                            <a href=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_pop04.png\" class=\"popup-image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening_info04.png\" alt=\"\" \/>\r\n                            <\/a>\r\n                        <\/dd>\r\n                    <\/dl>\r\n                    <h3 id=\"CHARA_1361_013\" class=\"sec_h3charatxt\">Personagens relacionados<\/h3>\r\n                    <h4 id=\"CHARA_1361_014\" class=\"sec_h4charatxt\">Alear<\/h4>\r\n                    <p id=\"CHARA_1361_015\" class=\"sec_charatxt\">Descendente do drag\u00e3o divino que despertou de um longo sono. Invoca Lucina e os outros emblemas para trazer paz ao mundo.<\/p>\r\n                    <h4 id=\"CHARA_1361_016\" class=\"sec_h4charatxt\">Lumera<\/h4>\r\n                    <p id=\"CHARA_1361_017\" class=\"sec_charatxt\">Drag\u00e3o divino monarca, soberana do reino sagrado de Lythos. Ela \u00e9 m\u00e3e de Alear e a hero\u00edna que certa vez salvou todo o continente de Elyos com a ajuda de Lucina e dos outros emblemas.<\/p>\r\n                <\/section>\r\n            <\/article>\r\n        <\/main>","protected":false},"excerpt":{"rendered":"Hero\u00edna de emblema Do despertar Lucina Aparece em Fire Emblem AwakeningFire Emblem Engage Sharena apresenta: Do despertar Lucina O anel da princesa vener\u00e1vel \u00e9 um artefato antigo do continente de Elyos e dentro dele habita Lucina, um dos 12 emblemas que outrora salvaram Elyos! Lucina mudou o futuro ao voltar no tempo para salvar o [&hellip;]","protected":false},"author":1,"featured_media":65717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_locale":"pt_BR","_original_post":"https:\/\/guide.fire-emblem-heroes.com\/?p=65681","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1512,1384,1527,1431,1390],"tags":[1545],"class_list":["post-65691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex_works_engage","category-character","category-emblem_heroes","category-ex_works_awakening","category-stay_heroes","tag-heroina-de-emblema","pt-BR"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/guide.fire-emblem-heroes.com\/wp-content\/uploads\/lucina_of_awakening.png","jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/pa0Mj3-h5x","jetpack_likes_enabled":false,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/65691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/comments?post=65691"}],"version-history":[{"count":1,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/65691\/revisions"}],"predecessor-version":[{"id":65698,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/posts\/65691\/revisions\/65698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media\/65717"}],"wp:attachment":[{"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/media?parent=65691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/categories?post=65691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guide.fire-emblem-heroes.com\/wp-json\/wp\/v2\/tags?post=65691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}